{"id":1454,"date":"2017-10-29T17:51:36","date_gmt":"2017-10-29T16:51:36","guid":{"rendered":"http:\/\/www.euroexit.org\/?p=1454"},"modified":"2017-10-29T17:51:36","modified_gmt":"2017-10-29T16:51:36","slug":"die-piketty-toeter-sind-wieder-unterwegs-die-nzz-fuerchtet-um-die-neoliberale-hegemonie-und-startet-einen-angriff","status":"publish","type":"post","link":"https:\/\/www.euroexit.org\/index.php\/2017\/10\/29\/die-piketty-toeter-sind-wieder-unterwegs-die-nzz-fuerchtet-um-die-neoliberale-hegemonie-und-startet-einen-angriff\/","title":{"rendered":"DIE PIKETTY-T\u00d6TER SIND WIEDER UNTERWEGS. Die NZZ f\u00fcrchtet um die neoliberale Hegemonie und startet einen Angriff"},"content":{"rendered":"<p>Es ist nun schon wieder einige Jahre her. Thomas Piketty sorgt f\u00fcr Aufruhr unter seinen Zunft-Kollegen. Er weist nach, dass die Ungleichheit in einer Reihe von L\u00e4ndern massiv zunimmt, dass insbesondere das oberste Prozent und das oberste Promille soviel vom Einkommen einsacken wie schon seit einem Jahrhundert nicht mehr. Und er stellt die wenig gewagte Prognose: Es geht so weiter, und der Kapitalismus \u2013 den er verteidigt \u2013 wird sich damit Probleme einhandeln.<\/p>\n<p>Insbesondere in den USA macht er damit Furore. Es ist keineswegs aus der Welt, den Bei\u00adnahe-Erfolg des Bernie Sanders mit diesem enormen <em>Bestselling<\/em> in Verbindung zu bringen. Beide Geschehnisse stammen aus derselben Stimmung. Pikettys Buch wurde zum Gefahr f\u00fcr die Eliten. Man muss also etwas dagegen tun.<\/p>\n<p>Die ersten Angriffe von Journalisten der \u201eFinancial Times\u201c waren zu durchsichtig und prall\u00adten 2014 ab. Noch plumper machten es die Zunft-Genossen, manche \u00d6konomen, die auch ganz ersichtlich von Neid auf den Erfolg getrieben waren. Der Leib- und Magen-\u00d6konom des DGB und der SPD, Peter Bofinger, ein BRD-\u201eWirtschaftsweiser\u201c, der vor zwei Jahrzehnten auch ein \u201eManifest\u201c f\u00fcr den Euro geschrieben hat, manipulierte und log offenbar bewusst. Im \u201eSpiegel\u201c vom 2. Juni 2014 zitierte er als Beleg f\u00fcr angeblich widerspr\u00fcchliche Daten eine Graphik aus Pikettys Buch. Doch die wenige Seiten sp\u00e4ter in einer weiteren Graphik aufschei\u00adnenden von ihm als fehlend monierten Daten l\u00e4sst er beiseite. Dies war, wie gesagt, gar zu offensichtlich.<\/p>\n<p>Piketty ist in seinen theoretischen \u00dcberlegungen oberfl\u00e4chlich. Als Keynesianer verteidigt er \u00fcberdies das System, muss es wohl tun. Von der theoretischen Seite her w\u00e4re er also sehr leicht angreifbar. Aber seine eigentliche Leistung besteht in einem \u00fcber viele Jahre hinweg gesammelten Daten-Thesaurus. Er begann mit Frankreich und sah sich dann andere L\u00e4nder an. Diese <em>Einkommens<\/em>-Daten aber lagen nicht auf der Stra\u00dfe. Die mussten gesammelt und aufbereitet werden. Dazu muss man sie bearbeiten, und da gibt es selbstverst\u00e4ndlich schwie\u00adrige Fragen. Piketty weist selbst wiederholt darauf hin. Um diese unvermeidbaren Probleme zu illustrieren, kann man auf ein \u00fcberaus ber\u00fchmtes Theorem hinweisen. Der <em>Kondratieff-Zyklus<\/em>, die langen Wellen der kapitalistischen Entwicklung, ergeben sich mittel- und kurz\u00adfristig aus schlie\u00dflich sehr oft chaotisch anmutenden Bewegungen. Die muss man versuchen, auseinander zu legen. Man kann, nach einer Bearbeitung dieser Daten, auch begr\u00fcndet der Meinung sein, der Kondratieff-Zyklus sei ein statistisches Artefakt. Ich f\u00fcr mich w\u00fcrde sagen: Ich wei\u00df nicht, ob \u201eder Kondratieff\u201c <em>als Zyklus<\/em> existiert \u2013 eher nicht.<\/p>\n<p>So steht es allerdings mit Pikettys Daten keineswegs. Sie sind so gut begr\u00fcndet, dass \u00fcber die Entwicklungs-Tendenzen auch keinerlei Dissens besteht, nicht einmal bei Konservativen. Allerdings sind einzelne Abschnitte, etwa im 19. Jahrhundert, schlecht dokumentiert. Auch vereinzelte Datenpunkte etwa zwischen 1969 und 1988 kann man offenbar in Frage stellen und anders rekonstruieren. Das tat <em>Sutch<\/em> in einem Arbeitspapier von 2015, das jetzt (2017) eben in einer sozialwissenschaftlichen Zeitschrift erschien. Besonders freundlich gesinnt ist <em>Sutch<\/em> seinem Kollegen nicht. Aber er bleibt halbwegs seri\u00f6s. Um es zu wiederholen: Die Trends der Entwicklung werden nicht nur best\u00e4tigt. Sie werden z. B. f\u00fcr Anfang der 1980er sogar akzentuiert: Es wird noch deutlicher, dass die US-Entwicklung, die massive Umver\u00adteilung nach ganz oben hin, vor allem auch ein Ergebnis der Reagan-Politik war. In anderen L\u00e4ndern kann man die Spuren der Politik ebenso deutlich erkennen: in Gro\u00dfbritannien jene von Thatcher \/ Blair; in der BRD jene von Kohl \/ Schr\u00f6der \/ Fischer; usf.<\/p>\n<p>Diese Korrekturen, welche Piketty also best\u00e4tigen, ihm aber das eine oder andere Ungeschick bei der Konstruktion anlasten, nimmt nun die die NZZ vom 25. Oktober 2017 zum Anlass, eine schwere Attacke zu reiten: \u201eSchlampigkeit\u201c ist noch der geringste der Vorw\u00fcrfe. Auf der Titelseite (!) der Zeitung hei\u00dft es: \u201eSeine Glaubw\u00fcrdigkeit hat mit den j\u00fcngsten Vorw\u00fcrfen zu seinem Umgang mit den Daten jedenfalls gelitten.\u201c Und dann kommt in derselben Ausgabe noch ein Artikel, S. 11. Dort wird vom selben Journalisten gar der Vorwurf des \u201eBetrugs\u201c erhoben. Die Sto\u00dfrichtung ist klar: Man muss ihn madig machen, vor allem seine Daten \u2013 denn, wie gesagt, Piketty ist ja ohnehin ein Kapitalismus-Verteidiger. \u201eDie empirische Arbeit mit den historischen Arbeiten (ist) seine gr\u00f6\u00dfte Schw\u00e4che.\u201c<\/p>\n<p>Die Sto\u00dfrichtung ist ganz klar und braucht nicht weiter besprochen zu werden. Aus einer akademischen Auseinandersetzung \u00fcber einzelne methodische Fragen wird ein hinterh\u00e4ltiger Generalangriff. Das ist auch sprachlich besonders deutlich. Wo <em>Sutch<\/em> im Englischen in einem technischen Sinn von \u201emanipulating the data\u201c spricht, also \u201edie Daten handhaben\u201c, wird in der Zeitung im Deutschen ein \u201eManipulieren\u201c daraus. In dieser Hinsicht ist die NZZ \u00fcber\u00adhaupt ganz gro\u00df. Ich erinnere mich: Als 1994 die EU im Zusammenspiel mit den nationalen Politikern die Kaskade der Volksabstimmung so ansetzte, dass m\u00f6glichst das gew\u00fcnschte Ergebnis herauskommen sollte, \u00fcberschrieb die NZZ das 52 : 48 Ergebnis in Schweden so: \u201eDeutliche Mehrheit f\u00fcr die EU.\u201c Als dann die Norweger unerwartet 52 : 48 gegen die EU stimmten, hie\u00df die \u00dcberschrift: \u201eKnappe Ablehnung des Beitritts\u201c\u2026<\/p>\n<p>Warum die lange Auseinandersetzung mit den Zeitungs-Manipulationen eines sich gerne als seri\u00f6s pr\u00e4sentierenden neoliberalen Kampfblatts? Es zeigt sich, dass die Patrone dieser Zeitung und ihre Lohnschreiber sich Sorgen um die Hegemonie machen. Wenn ein Buch, das doch einigerma\u00dfen komplex ist und \u00fcberdies auch noch, je nach Sprache, 700 \u2013 900 Seiten zwischen den Deckeln hat, einen solchen Erfolg einf\u00e4hrt, f\u00fchlt sich das System gef\u00e4hrdet, wenn da eine gewisse Kritik ge\u00e4u\u00dfert wird. Am 5. M\u00e4rz 2014, in einer Rezension des Buchs in diesem Blatt, der NZZ, hatte es noch gehei\u00dfen: \u201eAuch als Wirtschaftsprofessor darf man Sozialist sein\u201c &#8211; und der Rezensent f\u00fcgt im Nachsatz hinzu: \u201ein Frankreich\u201c! Kann man die Verh\u00e4ltnisse ungewollte besser charakterisieren?<\/p>\n<p>Arbeit im antihegemonialen Sinn ist also wichtig und zeitigt auf die Dauer auch Wirkung.<\/p>\n<p>Albert F. Reiterer<\/p>\n<p>&nbsp;<\/p>\n<p><em>Kondratieff, N. D.<\/em> (1979), The Long Waves in Economic Life. In: Review II, 519 \u2013 562 (\u00dcbersetzung von 1926, Die langen Wellen der Konjunktur. In: Archiv f\u00fcr Sozialwissenschaft und Sozialpolitik LVI, 573 \u2013 609).<\/p>\n<p><em>Piketty, Thomas<\/em> (2013), Le capital au xxi<sup>e<\/sup> si\u00e8cle. Paris: Seuil.<\/p>\n<p><em>Sutch, Richard<\/em> (2017), The One-Percent Across Two Centuries: A Replication of Thomas Piketty\u2019s Data on the Distribution of Wealth for the United States. In: Social Science History 41, 587 \u2013 613. Als Entwurf bzw. Arbeitspapier bereits am 12. Dez. 2015.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es ist nun schon wieder einige Jahre her. Thomas Piketty sorgt f\u00fcr Aufruhr unter seinen Zunft-Kollegen. Er weist nach, dass &hellip; <a href=\"https:\/\/www.euroexit.org\/index.php\/2017\/10\/29\/die-piketty-toeter-sind-wieder-unterwegs-die-nzz-fuerchtet-um-die-neoliberale-hegemonie-und-startet-einen-angriff\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDIE PIKETTY-T\u00d6TER SIND WIEDER UNTERWEGS. Die NZZ f\u00fcrchtet um die neoliberale Hegemonie und startet einen Angriff\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1454","post","type-post","status-publish","format-standard","hentry","category-home"],"author_meta":{"display_name":"Albert Reiterer","author_link":"https:\/\/www.euroexit.org\/index.php\/author\/albert\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.euroexit.org\/index.php\/category\/home\/\" class=\"advgb-post-tax-term\">Home<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Home<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Ver\u00f6ffentlicht 9\u00a0Jahren vor","modified":"Aktualisiert 9\u00a0Jahren vor"},"absolute_dates":{"created":"Ver\u00f6ffentlicht am 29. Oktober 2017","modified":"Aktualisiert am 29. Oktober 2017"},"absolute_dates_time":{"created":"Ver\u00f6ffentlicht am 29. Oktober 2017 17:51","modified":"Aktualisiert am 29. Oktober 2017 17:51"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/1454"}],"collection":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/comments?post=1454"}],"version-history":[{"count":0,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/1454\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/media?parent=1454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/categories?post=1454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/tags?post=1454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}