{"id":2334,"date":"2020-06-19T13:33:46","date_gmt":"2020-06-19T11:33:46","guid":{"rendered":"https:\/\/www.euroexit.org\/?p=2334"},"modified":"2020-06-19T13:34:34","modified_gmt":"2020-06-19T11:34:34","slug":"mehrheit-fuer-italexit","status":"publish","type":"post","link":"https:\/\/www.euroexit.org\/index.php\/2020\/06\/19\/mehrheit-fuer-italexit\/","title":{"rendered":"Mehrheit f\u00fcr Italexit!"},"content":{"rendered":"\n<p>Was die Italienerinnen und Italiener vom Merkel-Macron-Plan halten<\/p>\n\n\n\n<p>Im Falle eines Referendums w\u00fcrden 48% f\u00fcr den Austritt und 44% f\u00fcr den Verbleib stimmen, so eine Studie der Univerit\u00e4t Siena.<\/p>\n\n\n\n<p>[Bild: &#8222;Die j\u00fcnste Falle der EU&#8220;. Damit ist der angebliche 750-Mrd-Plan der EU gemeint. Denn in Italien ist, trotz der Propaganda der Regierung, sehr wohl bekannt, dass die Gelder gro\u00dfteils an die typischen Bedingungen gekn\u00fcpft sind, die das Land entm\u00fcndigen und die neoliberale Zerst\u00f6rung fortsetzen.]<\/p>\n\n\n\n<p>\u00dcbersetzung eines Artikel aus <a href=\"https:\/\/www.lastampa.it\/topnews\/2020\/06\/17\/news\/quegli-italiani-che-vorrebbero-uscire-dall-unione-europea-1.38977006?fbclid=IwAR0XPyN7GZbKObfTBxDy1SotgMNN0k7nrVp_Xu_JZ030PriCn7_ZsDdneBo\">La Stampa<\/a> vom 17.6.20, erstellt von Rainer Brunath:<\/p>\n\n\n\n<p><strong>Diejenigen Italiener, die die Europ\u00e4ische Union verlassen m\u00f6chten<\/strong><\/p>\n\n\n\n<p><strong>Ein verwirrtes und befangenes Land ergibt sich aus dem j\u00fcngsten Bericht, den die Iai<a href=\"#_ftn1\"><strong>[1]<\/strong><\/a> an der Universit\u00e4t von Siena in Auftrag gegeben hat. Wenn Sie \u00fcber &#8222;Italexit&#8220; abstimmen, w\u00e4ren 48 Prozent daf\u00fcr und 44 dagegen, m\u00f6chten aber die Euro(W\u00e4hrung) behalten.<\/strong><\/p>\n\n\n\n<p>\u00dcberraschung: Gerade in der Zeit, in der Europa sein beeindruckendstes Wiederherstellungshilfeprogramm startete, erkl\u00e4rten sich die Italiener in einer Umfrage, die vom Istituto Affari Internazionali an der Universit\u00e4t von Siena mit Unterst\u00fctzung der Compagnia Fondazione San Paolo in Auftrag gegeben wurde, in Mehrheit f\u00fcr den Austritt Italiens aus der Europ\u00e4ischen Union (aber nicht aus dem Euro &#8230;)<\/p>\n\n\n\n<p>Tats\u00e4chlich glauben 79 Prozent, dass die Bem\u00fchungen der EU, Italien bei der Bew\u00e4ltigung der Krise zu unterst\u00fctzen, wenig oder gar nicht angemessen waren. &#8222;Die Gr\u00fcnde f\u00fcr diesen R\u00fcckgang des Konsenses f\u00fcr die EU &#8211; hei\u00dft es in dem Bericht &#8211; lassen sich zumindest teilweise auf die weit verbreitete \u00dcberzeugung zur\u00fcckf\u00fchren, dass Italien im Rahmen des Notstands von Europa und anderen europ\u00e4ischen L\u00e4ndern ungerecht behandelt wurde Gesundheit: 71% der Stichprobe glauben dies. &#8222;Hinzu kommt die Tatsache, dass &#8222;die Mehrheit der Italiener EU-Hilfe akzeptieren w\u00fcrde, selbst wenn dies zu einer verst\u00e4rkten Kontrolle Br\u00fcssels \u00fcber unsere Wirtschaftspolitik f\u00fchren w\u00fcrde.\u201c<\/p>\n\n\n\n<p>Euroskeptische Gef\u00fchle \u2013 liest man&nbsp; &#8211; &#8222;wachsen betr\u00e4chtlich und der Anteil derjenigen, die aufgrund der Unterschiede zwischen den Mitgliedstaaten nicht an eine europ\u00e4ische Integration glauben, steigt. Eine relative Mehrheit der Stichprobe w\u00fcrde f\u00fcr einen Austritt aus der Europ\u00e4ischen Union sein, w\u00e4hrend ein entgegengesetztes Ergebnis verzeichnet wird in Bezug auf den Euro.&nbsp; Parallel dazu wachsen die positiven Meinungen zum Brexit und die Zahl derer, die glauben, dass Italien an der Mutterbrust der EU ungerecht behandelt wurde.<\/p>\n\n\n\n<p>Es sollte spezifiziert werden &#8211; bemerkt Professor Pierangelo Isernia, der die Forschung leitete &#8211; &#8222;dass die Ergebnisse bis Ende April zur\u00fcckreichen, also am Vorabend von Phase 2.&#8220; Es ist daher nicht ausgeschlossen, dass sp\u00e4tere Entwicklungen im Rahmen des Wiederherstellungsfonds zur \u00c4nderung der (Meinungs)-Gegebenheit&nbsp; beigetragen h\u00e4tten, aber gem\u00e4\u00df dem Komplex der Forschung entsteht&nbsp; der Eindruck, dass wir mit einer Meinung konfrontiert sind, die nicht sehr nachdenklich ist (der Art, dass die Mehrheit den Austritt aus der EU&nbsp; w\u00fcnscht, aber nicht aus dem Euro) und als solche nicht unbedingt anf\u00e4llig ist f\u00fcr Abweichungen im Zusammenhang mit rationalen Argumenten.<\/p>\n\n\n\n<p>&#8222;Es gibt eine Darstellung Italiens, die insbesondere drei Aspekte widerspiegelt &#8211; beobachtete der \u00d6konom Lorenzo Bini Smaghi bei der Kommentierung des Berichts -, n\u00e4mlich Desinformation, Manipulation und Misstrauen. Diese Meinungen beruhen auf Eindr\u00fccken und instinktiven Urteilen \u00fcber das v\u00f6llige Fehlen von Beweisen welche die \u00f6ffentliche Debatte (in eine Richtung) \u00fcbersetzt, die sich stark von der anderer L\u00e4nder unterscheidet und die von einer (interessierten) politischen Klasse beeinflusst wird.&#8220; Der Trend &#8211; f\u00fcgt Bini Smaghi hinzu &#8211; &#8222;scheint mir darin zu bestehen, das Misstrauen der Institutionen nach Europa zu verlagern, und ich finde es eine gef\u00e4hrliche Tatsache&#8220;.<\/p>\n\n\n\n<p>&#8222;Basierend auf diesem Indikator, der in der Wirtschaft als zuf\u00e4lliger Beweis definiert wird\u201c &#8211; sagt die Ex-Ministerin <strong>Elsa Fornero<\/strong> &#8211; \u201eglaube ich, dass der Bericht die Wahrheit sagt, und ich glaube auch, dass er das Ergebnis der von der gelbgr\u00fcnen Regierung implantierten Mystifizierung ist, (folgert) aber auch aus der Krise von 2008 &#8222;. In jenen Jahren, erinnert sich <strong>Fornero<\/strong>, wurde ein M\u00e4rchen (Narrativ) erstellt, das die Sparma\u00dfnahmen und die Notwendigkeit sah, sich der Frage der Staatsverschuldung &#8222;im Spiegelbild eines schlechten Deutschlands und einer Belagerung Italiens&#8220; zu stellen. Noch heute ist es schwierig, aus dieser Darstellung herauszukommen, denn (Frau) <strong>Fornero<\/strong>, die sich an die auf dem Ibero-Amerikanischen-Institut-Treffen anwesende stellvertretende Ministerin Marina Sereni wandte und \u00fcber die Bedeutung der Politik f\u00fcr einen Richtungswechsel intervenierte: &#8222;Die Demokratische Partei &#8211; sagte sie&nbsp; &#8211; muss die Verantwortung \u00fcbernehmen, muss dem Land mitteilen, dass Reformen Opfer beinhalten und dass sie im Herzen Europas verwurzelt sind.<\/p>\n\n\n\n<p>Als Antwort erinnerte Marina Sereni daran, dass in wenigen Monaten mehr Tabus in Europa gefallen sind, als man sich vorstellen kann (&#8222;denken Sie nur an die Eurobonds&#8220;), als sie die Rolle Italiens bei den Verhandlungen unterstrich, die das Gewicht der deutschen F\u00fchrung schleifen k\u00f6nnte in einem f\u00fcr uns wesensgleichen Rahmen. Alles jenes, zumindest nach den Umfragen zu urteilen, scheinen die Italiener nicht begriffen zu haben.<\/p>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p><a href=\"#_ftnref1\">[1]<\/a>&nbsp;&nbsp;&nbsp;&nbsp; &nbsp; Ibero-Amerikanisches-Institut<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Was die Italienerinnen und Italiener vom Merkel-Macron-Plan halten Im Falle eines Referendums w\u00fcrden 48% f\u00fcr den Austritt und 44% f\u00fcr &hellip; <a href=\"https:\/\/www.euroexit.org\/index.php\/2020\/06\/19\/mehrheit-fuer-italexit\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eMehrheit f\u00fcr Italexit!\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":2335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-2334","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home"],"author_meta":{"display_name":"Wilhelm Langthaler","author_link":"https:\/\/www.euroexit.org\/index.php\/author\/wilhelm\/"},"featured_img":"https:\/\/www.euroexit.org\/wp-content\/uploads\/2020\/06\/trappola-euro-600x400-1-300x200.jpg","coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.euroexit.org\/index.php\/category\/home\/\" class=\"advgb-post-tax-term\">Home<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Home<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Ver\u00f6ffentlicht 6\u00a0Jahren vor","modified":"Aktualisiert 6\u00a0Jahren vor"},"absolute_dates":{"created":"Ver\u00f6ffentlicht am 19. Juni 2020","modified":"Aktualisiert am 19. Juni 2020"},"absolute_dates_time":{"created":"Ver\u00f6ffentlicht am 19. Juni 2020 13:33","modified":"Aktualisiert am 19. Juni 2020 13:34"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/2334"}],"collection":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/comments?post=2334"}],"version-history":[{"count":2,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/2334\/revisions"}],"predecessor-version":[{"id":2337,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/2334\/revisions\/2337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/media\/2335"}],"wp:attachment":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/media?parent=2334"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/categories?post=2334"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/tags?post=2334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}