{"id":318,"date":"2015-06-18T17:02:50","date_gmt":"2015-06-18T17:02:50","guid":{"rendered":"http:\/\/www.euroexit.org\/?p=318"},"modified":"2015-06-18T17:02:50","modified_gmt":"2015-06-18T17:02:50","slug":"die-krise-der-eu","status":"publish","type":"post","link":"https:\/\/www.euroexit.org\/index.php\/2015\/06\/18\/die-krise-der-eu\/","title":{"rendered":"Die Krise der EU"},"content":{"rendered":"<p>von Annette Groth, Mitglied des deutschen Bundestages (Die Linke)<\/p>\n<p>&nbsp;<\/p>\n<p>Die Europ\u00e4ische Union befindet sich in einer tiefen \u00f6konomischen und demokratischen Legitimationskrise. Mit der Verabschiedung des Vertrags von Lissabon wurde ein autorit\u00e4res, neoliberales Gesellschaftsbild endg\u00fcltig vertraglich festgelegt, das vor allem auf die Interessen der transnational arbeitenden internationalen Gro\u00dfkonzerne angelegt ist. Starke \u00d6konomien in der EU profitieren von dieser Grundlage, w\u00e4hrend die schw\u00e4cheren immer weiter ins Abseits gedr\u00e4ngt werden.<\/p>\n<p>Die heutige Finanz- und Wirtschaftskrise ist eine Folge dieser falschen \u00f6konomischen Grundlage der Europ\u00e4ischen Union. Durch die st\u00e4ndig zunehmende aggressive Exportpolitik vor allem auch Deutschlands, wurden die finanziellen und \u00f6konomischen Grundlagen der schw\u00e4cheren Staaten, allen voran Griechenland, Italien, Spanien und Portugal, immer weiter zerst\u00f6rt. Die \u201egriechische Krise\u201c ist vor allem auch eine Krise des falschen vertraglichen und \u00f6konomischen Grundkonzeptes der Europ\u00e4ischen Union.<\/p>\n<p>Eine wesentliche Ursache f\u00fcr die Krise in den s\u00fcdeurop\u00e4ischen L\u00e4ndern ist die drastische Lohnsenkungspolitik der Bundesregierung. Stichwort hierf\u00fcr ist die Agenda 2010[i], die durch die rot-gr\u00fcne Koalition unter Gerhard Schr\u00f6der begonnen und seitdem konsequent umgesetzt wurde. Diese fatale Lohnsenkungspolitik hat die \u201eBeggar-thy-neighbor-Politik\u201c massiv vorangetrieben. Diese protektionistische Politik soll zu einer Erh\u00f6hung der Leistungsbilanz\u00fcbersch\u00fcsse  f\u00fchren, mit der heimische \u00f6konomische Defizite auf andere Volkswirtschaften abgew\u00e4lzt werden. Wirtschaftsnobelpreistr\u00e4ger Stiglitz hat darauf hingewiesen, dass eine solche Politik letztendlich zu einer Importverminderung und damit mittel- bis langfristig auch zu einem R\u00fcckgang der Exporte bei gleichzeitiger nachhaltiger Einschr\u00e4nkung der Nachfrage im eigenen Land f\u00fchrt.[ii]<\/p>\n<p>Resultat einer solchen, an Wettbewerbsvorteilen der starken \u00d6konomien ausgerichteten, neoliberalen Wirtschafts- und Gesellschaftspolitik sind zwar auf der einen Seite riesige Au\u00dfenhandels\u00fcbersch\u00fcsse der starken Exportstaaten &#8211; so haben sich die Au\u00dfenhandels\u00fcbersch\u00fcsse Deutschlands von 2000 bis 2015 auf zwei Billionen Euro summiert[iii] &#8211; gleichzeitig sind jedoch die Au\u00dfenhandelsdefizite bei den schw\u00e4cheren \u00d6konomien exorbitant angestiegen. Deshalb ist Grundvoraussetzung f\u00fcr die L\u00f6sung der europ\u00e4ischen Finanz- und Wirtschaftskrise u.a. eine neue Wirtschaftspolitik in Deutschland mit dem Ziel, die Kaufkraft in Deutschland zu st\u00e4rken und zu einer ausgeglichenen Handelsbilanz zu kommen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Demokratie wird zerst\u00f6rt<\/strong><\/p>\n<p>Sp\u00e4testens mit dem Ausbruch der Krise sind die demokratischen Defizite der EU eklatant zutage getreten. Griechenland wurden Sparauflagen diktiert, ein mit den EU-Vertr\u00e4gen nicht zu vereinbarendes Gremium, die Troika, wurde implementiert und demokratische Entscheidungen des griechischen Parlaments aufgehoben. Seit dieser Zeit werden griechische Regierungen gezwungen, die Austerit\u00e4tspolitik der EU-Staaten umzusetzen und durch weitreichende Privatisierungen, Deregulierungen und Haushaltsk\u00fcrzungen Entwicklungsm\u00f6glichkeiten f\u00fcr die griechische Wirtschaft einzuschr\u00e4nken. Folge dieser falschen Politik der Troika sind Massenarbeitslosigkeit, Armut, zunehmende Obdachlosigkeit, ein zerst\u00f6rtes Gesundheitswesen und die systematische Abwicklung des Sozialstaates in Griechenland. Gegen diese Politik hat sich Widerstand formiert, der mit dem Wahlerfolg von Syriza auch im Parlament seinen Ausdruck fand.<\/p>\n<p>Ziel der neuen Regierung ist es, Griechenland von den katastrophalen gesamtwirtschaftlichen Kosten durch die \u201eaufoktroyierte staatliche Schrumpfpolitik\u201c[iv] zu befreien. Die bisherigen Finanzhilfen aus dem Rettungsfonds haben ausschlie\u00dflich der Finanzierung von auszuzahlenden Staatsschulden an die Gl\u00e4ubiger gedient[v] und damit ein gro\u00df angelegtes Umverteilungsprogramm von Privatgl\u00e4ubigern hin zu staatlichen Absicherungen dargestellt. F\u00fcr die Entwicklung der Infrastruktur in Griechenland und der Stimulierung der Wirtschaft wurden bisher keinerlei Finanzhilfen zur Verf\u00fcgung gestellt. Die bisherige Politik der starken Staaten der EU ist darauf ausgerichtet, den griechischen Absatzmarkt mittelfristig zu stabilisieren, aber eine eigenst\u00e4ndige \u00f6konomische Entwicklung der griechischen Wirtschaft nicht zu f\u00f6rdern, um weiterhin hohe Profite der exportorientierten Nationalkapitale abzusichern. Mit dieser Politik sollen die bisherigen Schulden sozialisiert werden, um gleichzeitig neue private Profitm\u00f6glichkeiten f\u00fcr die Gro\u00dfunternehmen m\u00f6glich zu machen.<\/p>\n<p>Folge dieser falschen Finanzpolitik ist die st\u00e4ndige Zunahme der Staatsverschuldung Griechenlands, die von 2006 (107,3 Prozent des BIP) bis 2015 (179,5 % des BIP) stetig  angestiegen ist. Allein im vergangenen Jahr hat aufgrund der falschen Politik der Troika die Neuverschuldung Griechenlands um 7 Milliarden Euro zugenommen.[vi]<\/p>\n<p>Die Troika und die neoliberalen Regierungen haben schon im Vorfeld des Wahlkampfes in die innergriechischen Debatten eingegriffen und sowohl direkt als auch indirekt vor einer Wahl von SYRIZA gewarnt. Ziel war es, die griechischen W\u00e4hlerinnen und W\u00e4hler einzusch\u00fcchtern, damit sie auf ihr Recht auf einen Kurswechsel verzichten.[vii]  Mit dieser Kampagne sollten Vorbereitungen getroffen werden, im Falle eines Wahlsieges von Syriza eine negative Stimmung in den anderen von der Krise betroffenen L\u00e4ndern zu erzeugen und zu verhindern, dass dort fortschrittliche Parteien wie z.B. Podemos in Spanien gute Wahlergebnisse erhalten.[viii] Die derzeit Herrschenden f\u00fcrchten eine Beispielwirkung von Griechenland und setzen alles daran, den W\u00e4hlenden zu vermitteln, dass auch eine Linksregierung gegen die Macht des neoliberalen Politikkartells keine Chance hat. Sie wollen durch ihre Politik ein Scheitern der Syriza-Regierung f\u00f6rdern und nehmen f\u00fcr die Sicherung ihrer Politik eine deutliche St\u00e4rkung von rechtspopulistischen und faschistischen Parteien und Gruppen in Griechenland und anderen Staaten der EU bewusst in Kauf.<\/p>\n<p>Die Troika hat mit ihrer Politik eine katastrophale Entwicklung in Griechenland eingeleitet: \u201eDie griechische Wirtschaftsleistung ist zwischen 2008 und 2014 um rund 25 Prozent kollabiert. Die Inlandsnachfrage brach preisbereinigt sogar um ein Drittel ein (2007-13), das sind 15 Prozentpunkte mehr als in den anderen europ\u00e4ischen Krisenl\u00e4ndern. Die Bruttoanlageinvestitionen schmolzen preisbereinigt um 65 Prozent (2007-14), die Besch\u00e4ftigung fiel um 20 Prozent.\u201c[ix] Auch das Institut f\u00fcr Makro\u00f6konomie und Konjunkturforschung (IMK) macht deutlich, dass \u201edie nominalen Bruttoeinkommen der griechischen Privathaushalte in nur vier Jahren von 2008 bis 2012 um ein knappes Viertel gesunken\u201c sind.[x]<\/p>\n<p>Toussaint weist in seinem Artikel weiterhin darauf hin, dass \u201eim Artikel 7 Punkt 9 den Staaten unter struktureller Anpassung vorgeschrieben wird, eine gr\u00fcndliche Pr\u00fcfung der Staatsschulden vorzunehmen, um zu kl\u00e4ren, warum die Verschuldung \u00fcberm\u00e4\u00dfig gestiegen ist, und Unregelm\u00e4\u00dfigkeiten aufzusp\u00fcren\u201c[xi]. Er bezieht sich dabei auf die \u201eVerordnung (EG) Nr. 472\/2013 des Europ\u00e4ischen Parlaments und des Rates vom 21. Mai 2013 \u00fcber den Ausbau der wirtschafts- und haushaltspolitischen \u00dcberwachung von Mitgliedstaaten im Euro-W\u00e4hrungsgebiet, die von gravierenden Schwierigkeiten in Bezug auf ihre finanzielle Stabilit\u00e4t betroffen oder bedroht sind.\u201c In dieser Verordnung werden die Mitgliedstaaten ausdr\u00fccklich in Artikel 7 Punkt 9 aufgefordert, dass \u201eein Mitgliedstaat, der einem makro\u00f6konomischen Anpassungsprogramm unterliegt, \u2026 eine umfassende Pr\u00fcfung seiner \u00f6ffentlichen Finanzen durchf\u00fchrt, um unter anderem die Gr\u00fcnde f\u00fcr die Entstehung des \u00fcberm\u00e4\u00dfigen Schuldenstandes zu analysieren und etwaige Unregelm\u00e4\u00dfigkeiten zu ermitteln.\u201c Die griechische Regierung hat mit ihrem Reformprogramm eine solche Pr\u00fcfung ausdr\u00fccklich vorgenommen, wird jedoch von der Troika daran gehindert, politisch und \u00f6konomisch sinnvolle Schlussfolgerungen aus dieser Analyse zu ziehen. W\u00fcrde eine solche Pr\u00fcfung durch die griechische Regierung akzeptiert, m\u00fcsste die neoliberale Austerit\u00e4tspolitik sofort beendet werden.<\/p>\n<p>In dem \u201e\u00d6konomInnenaufruf f\u00fcr Griechenland\u201c wurde die Troika ausdr\u00fccklich aufgefordert, die \u201eEntscheidung des griechischen Volkes, einen neuen Kurs einzuschlagen, zu respektieren und guten Glaubens in Verhandlungen mit der neuen Regierung Griechenlands zur L\u00f6sung des griechischen Schuldenproblems einzutreten. Die griechische Regierung besteht zu Recht auf neuen Konzepten, denn die bisherigen sind gescheitert\u201c.[xii]<\/p>\n<p>Die Syriza-Regierung versucht, mit ihrem Politikansatz eine Verst\u00e4ndigung zwischen Troika und Griechenland herbeizuf\u00fchren. Bei ihrem Kampf gegen die neoliberalen Dogmen geht es vor allem auch um die R\u00fcckgewinnung von Souver\u00e4nit\u00e4t des griechischen Staates gegen die Diktatur aus Troika und den Gremien der Eurozone. Ziel ist es, durch eine neue Wirtschafts- und Sozialpolitik die Verbesserung der Lebensverh\u00e4ltnisse der breiten Bev\u00f6lkerung in den Mittelpunkt der Politik zu stellen und eine jahrelange faktische Fremdherrschaft durch die Troika aus EU-Kommission, EZB und IWF zu beenden.[xiii]<\/p>\n<p>Ziel der Syriza-Regierung ist es, die humanit\u00e4re Krise zu bew\u00e4ltigen, die rezessionsgeschw\u00e4chte Wirtschaft zu st\u00e4rken, einen Kampf gegen die grassierende Korruption und Schattenwirtschaft in Griechenland zu organisieren und die Einf\u00fchrung eines \u00bbgerechten\u00ab Steuersystems voranzubringen. Dies soll durch die Verabschiedung eines Vierjahresplans auf den Weg gebracht werden, der zu einem ausgeglichenen Staatshaushalt f\u00fchren soll.[xiv] Diese Politik wurde von der Troika von Anfang an torpediert. Die Troika versucht, der neuen Regierung ihre Bedingungen zu diktieren und sie auf den \u201ealten\u201c Kurs der gescheiterten Regierung zur\u00fcckzudr\u00e4ngen. Die Strategie der Troika geht offiziell von der Diagnose aus, dass die Hauptursachen der Finanzkrise in Griechenland in einer undisziplinierten Fiskalpolitik, zu hohen L\u00f6hnen sowie einem Mangel an Strukturreformen zu suchen seien.[xv] In der offiziellen Behauptung der Troika ist die Krise also vollst\u00e4ndig \u201eMade in Greece\u201c.[xvi] Mit dieser Falschbehauptung soll von der wirklichen Ursache der Krise abgelenkt und die Politik der Exportorientierung der Hauptl\u00e4nder der EU weiter gesichert werden.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>EU braucht radikalen Kurswechsel<\/strong><\/p>\n<p>Die neoliberale Logik der EU muss beendet werden. Ziel muss ein radikaler Politikwechsel in der EU sein. Hierf\u00fcr ist eine Neuausrichtung der Finanzpolitik der EU notwendig. Es ist absurd, dass die EZB Banken mit billigem Geld zu Niedrigzinsen versorgt, die dieses Geld dann als teure Kredite an die Staaten weiterverleihen. In Zukunft m\u00fcssen die Staaten direkt bei der EZB die Finanzierung ihrer Haushalte sicherstellen k\u00f6nnen. Weiter muss eine weitgehende Demokratisierung der EZB durchgesetzt werden, bei der demokratisch gew\u00e4hlte Parlamente die Politik der EZB \u00fcberwachen und auch beeinflussen k\u00f6nnen.<\/p>\n<p>Die bisherige Politik der Troika muss endlich beendet werden. Die Akteure der Troika \u201eerpressten Minister, spielten sich zum Gesetzgeber auf und machten gemeinsame Sache mit den reichen Eliten. Die als Kontrolleure eingesetzten Technokraten aus IWF, EZB und EU-Kommission hatten in den Krisenstaaten eine Macht jenseits aller demokratischen Kontrolle\u201c[xvii]. Dieses undemokratische Instrument der Herrschenden muss seine Arbeit einstellen und die Verhandlungen zwischen Regierungen m\u00fcssen in die demokratischen Institutionen zur\u00fcckverlagert werden. Daf\u00fcr braucht es eine grundlegende Reform der Eurozone und der EU-Vertr\u00e4ge.<\/p>\n<p>[i] Siehe dazu: Michael Schlecht. Michael, Klartext zu Griechenland, 07.05.2015, S. 2 ff.<br \/>\n[ii] Siehe dazu: Joseph E Stiglitz, Carl E Walsh, Mikro\u00f6konomie: Band 1 zur Volkswirtschaftslehre, Oldenbourg Verlag, 2010, S. 508ff.<br \/>\n[iii] Siehe dazu: Michael Schlecht. Michael, Klartext zu Griechenland, 07.05.2015, S. 2 ff.<br \/>\n[iv] Hickel, Rudolf, Das Beispiel Griechenland: Die Rettungspolitik Finanzhilfen aus dem Rettungsfonds gegen staatliche Schrumpfpolitik ist gescheitert: Schuldenbew\u00e4ltigung durch St\u00e4rkung der wirtschaftlichen Wachstumskr\u00e4fte, S. 1,  o.Jahr.<br \/>\n[v] Ebd.<br \/>\n[vi] Ebd.<br \/>\n[vii] Toussaint, Eric, Und wenn Syriza die Europ\u00e4ische Union beim Wort nehmen und Griechenlands Schulden pr\u00fcfen w\u00fcrde?, 31.01.2015.<br \/>\n[viii] Ebd.<br \/>\n[ix] : Priewe Jan\/Stachelsky, Phillip, Griechische Depression \u2013 wenn die Chef\u00e4rzte versagen, M\u00e4rz 2015, S. 1.<br \/>\n[x] Instituts f\u00fcr Makro\u00f6konomie und Konjunkturforschung (IMK) in der Hans-B\u00f6ckler-Stiftung: Tassos Giannitsis, Stavros Zografakis: Greece: Solidarity and Adjustment in Times of Crisis (pdf), Studie gef\u00f6rdert vom Institut f\u00fcr Makro\u00f6konomie und Konjunkturforschung (IMK) in der Hans-B\u00f6ckler-Stiftung; IMK Study 38, M\u00e4rz 2015.<br \/>\n[xi] Ebd., S. 2.<br \/>\n[xii] \u00d6konomInnenaufruf f\u00fcr Griechenland,<br \/>\n[xiii] Redaktion Sozialismus: Syrizas Erfolg h\u00e4ngt auch vom gesellschaftlichen Druck ab, Zwischen Konfrontation und Kooperation, 01.02.2015<br \/>\n[xiv] Ebd.<br \/>\n[xv] Siehe dazu: Priewe Jan\/Stachelsky, Phillip, Griechische Depression \u2013 wenn die Chef\u00e4rzte versagen, M\u00e4rz 2015.<br \/>\n[xvi] Ebd.<br \/>\n[xvii] Harald Schumann, Harald, Die Troika: Macht ohne Kontrolle, in: Tagesspiegel, 24.02.2015.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>von Annette Groth, Mitglied des deutschen Bundestages (Die Linke) &nbsp; Die Europ\u00e4ische Union befindet sich in einer tiefen \u00f6konomischen und &hellip; <a href=\"https:\/\/www.euroexit.org\/index.php\/2015\/06\/18\/die-krise-der-eu\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDie Krise der EU\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-318","post","type-post","status-publish","format-standard","hentry","category-home"],"author_meta":{"display_name":"Wilhelm Langthaler","author_link":"https:\/\/www.euroexit.org\/index.php\/author\/wilhelm\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.euroexit.org\/index.php\/category\/home\/\" class=\"advgb-post-tax-term\">Home<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Home<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Ver\u00f6ffentlicht 11\u00a0Jahren vor","modified":"Aktualisiert 11\u00a0Jahren vor"},"absolute_dates":{"created":"Ver\u00f6ffentlicht am 18. Juni 2015","modified":"Aktualisiert am 18. Juni 2015"},"absolute_dates_time":{"created":"Ver\u00f6ffentlicht am 18. Juni 2015 17:02","modified":"Aktualisiert am 18. Juni 2015 17:02"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/318"}],"collection":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/comments?post=318"}],"version-history":[{"count":0,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/318\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/media?parent=318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/categories?post=318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/tags?post=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}