{"id":429,"date":"2015-07-13T15:23:56","date_gmt":"2015-07-13T15:23:56","guid":{"rendered":"http:\/\/www.euroexit.org\/?p=429"},"modified":"2015-07-13T15:23:56","modified_gmt":"2015-07-13T15:23:56","slug":"grexit-als-chance-auf-soziale-entwicklung","status":"publish","type":"post","link":"https:\/\/www.euroexit.org\/index.php\/2015\/07\/13\/grexit-als-chance-auf-soziale-entwicklung\/","title":{"rendered":"&#8222;Grexit&#8220; als Chance auf soziale Entwicklung"},"content":{"rendered":"<p>Pressemitteilung des steirischen KP\u00d6-Landtagsklubs:<\/p>\n<p>Die Grenzen der Demokratie ziehen die Europ\u00e4ische Zentralbank und der Internationale W\u00e4hrungsfonds<\/p>\n<p>&nbsp;<\/p>\n<p>Eine deutliche Mehrheit der griechischen Bev\u00f6lkerung hat am 5. Juli den von EU und IWF geforderten Forderungskatalog abgelehnt. Dieser umfasst Ma\u00dfnahmen, die noch mehr Armut bedeuten und keine Zukunftsperspektiven f\u00fcr das Land bieten. Dennoch bekommen die Griechinnen und Griechen, die f\u00fcr ein Nein gestimmt haben, nun ein Ja.<\/p>\n<p>Die Vorg\u00e4nge sind eine Bankrotterkl\u00e4rung der EU und der griechischen Regierung gleicherma\u00dfen. Demokratie wird in der EU so lange geduldet, so lange Kapitalinteressen unber\u00fchrt bleiben. Griechenland ist angesichts der unverhohlenen Erpressung in die Knie gezwungen worden. Premierminister Tsipras hat nun Bedingungen akzeptiert, die \u00fcber das hinausgehen, wor\u00fcber am 5. Juli abgestimmt wurde.<\/p>\n<p>Die EU hat unter deutscher F\u00fchrung ein Exempel statuiert. Anhand des griechischen Beispiels soll demonstriert werden, dass es aus dem neoliberalen Teufelskreis keinen Ausweg gibt. Wer es trotzdem versucht, wird auf internationaler B\u00fchne vorgef\u00fchrt. Das Signal: Es gibt keine Alternative zu Austerit\u00e4t und Neoliberalismus. Das soll ein f\u00fcr alle Mal in den K\u00f6pfen der Menschen in ganz Europa verankert werden.<\/p>\n<p>Erst durch ihr bedingungsloses Festhalten am Euro hat sich die griechische Regierung erpressbar gemacht. Ein &#8222;Grexit&#8220; h\u00e4tte dagegen mittelfristig die Chance auf eine soziale Entwicklung geboten. Sozial- und Demokratieabbau sind weder Naturgesetze noch wirtschaftliche Notwendigkeiten, wie den Menschen seit Jahrzehnten eingetrichtert wird. Eines sollte nun jeder EU-B\u00fcrgerin und jedem EU-B\u00fcrger klar geworden sein: Innerhalb der Korsetts von EU und Euro ist kein Sonderweg m\u00f6glich. Die Grenzen der Demokratie ziehen die Europ\u00e4ische Zentralbank und der Internationale W\u00e4hrungsfonds.<\/p>\n<p>Die steirische KP\u00d6 steht an der Seite der Griechinnen und Griechen, die f\u00fcr eine soziale, friedliche und demokratische Entwicklung ihres Landes eintreten. Eine solche wird es, in Griechenland wie in \u00d6sterreich, innerhalb der EU nicht geben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pressemitteilung des steirischen KP\u00d6-Landtagsklubs: Die Grenzen der Demokratie ziehen die Europ\u00e4ische Zentralbank und der Internationale W\u00e4hrungsfonds &nbsp; Eine deutliche Mehrheit &hellip; <a href=\"https:\/\/www.euroexit.org\/index.php\/2015\/07\/13\/grexit-als-chance-auf-soziale-entwicklung\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201e&#8222;Grexit&#8220; als Chance auf soziale Entwicklung\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-429","post","type-post","status-publish","format-standard","hentry","category-home"],"author_meta":{"display_name":"Wilhelm Langthaler","author_link":"https:\/\/www.euroexit.org\/index.php\/author\/wilhelm\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.euroexit.org\/index.php\/category\/home\/\" class=\"advgb-post-tax-term\">Home<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Home<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Ver\u00f6ffentlicht 11\u00a0Jahren vor","modified":"Aktualisiert 11\u00a0Jahren vor"},"absolute_dates":{"created":"Ver\u00f6ffentlicht am 13. Juli 2015","modified":"Aktualisiert am 13. Juli 2015"},"absolute_dates_time":{"created":"Ver\u00f6ffentlicht am 13. Juli 2015 15:23","modified":"Aktualisiert am 13. Juli 2015 15:23"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/429"}],"collection":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/comments?post=429"}],"version-history":[{"count":0,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/429\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/media?parent=429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/categories?post=429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/tags?post=429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}