{"id":716,"date":"2016-02-27T10:22:11","date_gmt":"2016-02-27T10:22:11","guid":{"rendered":"http:\/\/www.euroexit.org\/?p=716"},"modified":"2016-02-27T10:22:11","modified_gmt":"2016-02-27T10:22:11","slug":"dortmund-raus-aus-dem-euro","status":"publish","type":"post","link":"https:\/\/www.euroexit.org\/index.php\/2016\/02\/27\/dortmund-raus-aus-dem-euro\/","title":{"rendered":"Dortmund: &#8222;&#8230; raus aus dem Euro?\u201c"},"content":{"rendered":"<p>Ein Streitgespr\u00e4ch zur aktuellen Euro-Debatte mit Prof. Dr. Heinz J. Bontrup und Prof. Martin H\u00f6pner<\/p>\n<p>&nbsp;<\/p>\n<p><strong>&#8222;&#8230; raus aus dem Euro?\u201c &#8211; Die Plan-B-Diskussion und die Frage nach einer sozialvertr\u00e4glichen Aufl\u00f6sung der Euro-Zone<\/strong><\/p>\n<p>Montag, den 14. M\u00e4rz 2016, Beginn: 19.00 Uhr<\/p>\n<p>Veranstaltungsort: Auslandsgesellschaft Dortmund, Steinstr. 48 (Nordausgang Hbf., neben Cinestar)<\/p>\n<p>&nbsp;<\/p>\n<p>Die EU hat sich gerne als Friedensprojekt der europ\u00e4ischen V\u00f6lker dargestellt. Die Hoffnungen in die EU und den Euro waren gro\u00df. Wurden in der Nachkriegszeit in den Nationalstaaten Demokratie und Sozialstaat auf- und ausgebaut, so baut das Euro-System diese Schritt f\u00fcr Schritt ab. Immer deutlicher entwickeln sich in der EU zwei Pole, die un\u00fcbersehbare Zeichen einer Desintegration zwischen Zentrum und Peripherie sind. Die EU ist zu einem Synonym f\u00fcr Zwietracht und Verfall geworden.<\/p>\n<p>Auf dem Hintergrund der Griechenland-Krise wurde die Frage eines \u201eGrexit\u201c aufgeworfen und die Frage gestellt, ob \u201eein linke Euro\u201c m\u00f6glich ist. Inzwischen sind Initiativen wie Plan-B (Lafontaine\/M\u00e9lenchon) und DiEM 25 (Varoufakis) oder \u201eEuroexit\u201c gegen Sozialabbau entstanden. Die vor allem von Gewerkschaftern getragene Initiative \u201eEuropa neu begr\u00fcnden\u201c plant in diesem Jahr eine gr\u00f6\u00dfere Konferenz.<\/p>\n<p>Mit einem Streitgespr\u00e4ch zwischen Prof. Dr. Heinz-J. Bontrup (Sprecher der Memorandum-Gruppe) und Prof. Dr. Martin H\u00f6pner wollen wir Sachinformationen und Orientierungshilfen in der aktuellen Debatte um die Zukunft des Euro geben.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Heinz-J. Bontrup, Prof. Dr. rer.pol, Dipl.-\u00d6konom und Dipl.-Betriebswirt. Langj\u00e4hrige Praxiserfahrung in der Industrie, u.a. als Personalvorstand und Arbeitsdirektor in der Stahlindustrie. Seit 1996 Hochschullehrer f\u00fcr Wirtschaftswissenschaft an der Fachhochschule Gelsenkirchen. Sprecher der Arbeitsgruppe Alternative Wirtschaftspolitik<\/em><\/p>\n<p><em>Ausgew\u00e4hlte Ver\u00f6ffentlichungen:u.a.: Arbeit, Kapital und Staat. Pl\u00e4doyer f\u00fcr eine demokratische Wirtschaft \/   Krisenkapitalismus und EU-Verfall \/ Pikettys-Kapitalismusanalyse \/ Der diskreditiere Staat \/ Wo geht es hier bitte zur Marktwirtschaft? \/ Zukunftsf\u00e4higes NRW? Politik und Wirtschaft zwischen Schuldenbremse und Demographie-Mythen<\/em><\/p>\n<p><em> <\/em><\/p>\n<p><em>Martin H\u00f6pner studierte Politikwissenschaft und Germanistik an der Universit\u00e4t Heidelberg. Er promovierte zum Thema: \u201eWer beherrscht die Unternehmen? Shareholder Value, Managerherrschaft und Mitbestimmung in Deutschland\u201c. Es folgte ein Forschungsaufenthalt am Center for European Studies der Harvard University und die Habilitation zum Thema: \u201eOrganisierter Kapitalismus in Deutschland: Komplementarit\u00e4t, Politik, Niedergang\u201c. <\/em><\/p>\n<p><em>Seit 2008 ist H\u00f6pner Leiter einer Forschungsgruppe zur \u201ePolitischen \u00d6konomie der europ\u00e4ischen Integration\u201c am Max-Planck-Institut f\u00fcr Gesellschaftsforschung (MPIfG) und seit 2013 au\u00dferplanm\u00e4\u00dfiger Professor f\u00fcr Wirtschaft- und Sozialwissenschaften an der Universit\u00e4t zu K\u00f6ln<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Veranstalter: Attac Regionalgruppe Dortmund AG Globalisierung konkret,   DGB Stadtverband Dortmund, NachDenkTreff*<\/p>\n<p><strong> <\/strong><\/p>\n<p>* Der NachDenkTreff ist eine Einladung, viele Dinge anders zu sehen.<\/p>\n<p>Eine \u00c4hnlichkeit mit der Internetseite \u201e<a href=\"http:\/\/www.nachdenkseiten.de\/\">www.nachdenkseiten.de<\/a>\u201c ist dabei nicht zuf\u00e4llig, sondern beabsichtigt und wird zur werkt\u00e4glichen Lekt\u00fcre empfohlen. Informationen und Einladungen k\u00f6nnen Sie unter folgender E-Mail-Anschrift anfordern: <a href=\"mailto:NachDenkTreff@gmx.de\">NachDenkTreff@gmx.de<\/a><\/p>\n<p>Weitere interessante Veranstaltungen in und um Dortmund unter: <a href=\"http:\/\/www.dortmund-initiativ.de\/\">www.dortmund-initiativ.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Streitgespr\u00e4ch zur aktuellen Euro-Debatte mit Prof. Dr. Heinz J. Bontrup und Prof. Martin H\u00f6pner &nbsp; &#8222;&#8230; raus aus dem &hellip; <a href=\"https:\/\/www.euroexit.org\/index.php\/2016\/02\/27\/dortmund-raus-aus-dem-euro\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eDortmund: &#8222;&#8230; raus aus dem Euro?\u201c\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-716","post","type-post","status-publish","format-standard","hentry","category-home"],"author_meta":{"display_name":"Wilhelm Langthaler","author_link":"https:\/\/www.euroexit.org\/index.php\/author\/wilhelm\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.euroexit.org\/index.php\/category\/home\/\" class=\"advgb-post-tax-term\">Home<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Home<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Ver\u00f6ffentlicht 10\u00a0Jahren vor","modified":"Aktualisiert 10\u00a0Jahren vor"},"absolute_dates":{"created":"Ver\u00f6ffentlicht am 27. Februar 2016","modified":"Aktualisiert am 27. Februar 2016"},"absolute_dates_time":{"created":"Ver\u00f6ffentlicht am 27. Februar 2016 10:22","modified":"Aktualisiert am 27. Februar 2016 10:22"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/716"}],"collection":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/comments?post=716"}],"version-history":[{"count":0,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/716\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/media?parent=716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/categories?post=716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/tags?post=716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}