{"id":742,"date":"2016-04-06T14:58:24","date_gmt":"2016-04-06T12:58:24","guid":{"rendered":"http:\/\/www.euroexit.org\/?p=742"},"modified":"2017-02-20T01:10:05","modified_gmt":"2017-02-20T00:10:05","slug":"wahrungsunion-und-die-verelendung-der-europaischen-peripherie","status":"publish","type":"post","link":"https:\/\/www.euroexit.org\/index.php\/2016\/04\/06\/wahrungsunion-und-die-verelendung-der-europaischen-peripherie\/","title":{"rendered":"W\u00c4HRUNGSUNION UND DIE VERELENDUNG DER EUROP\u00c4ISCHEN PERIPHERIE"},"content":{"rendered":"<p>Nicht nur von Verteidigern dieses Systems und der EU im Besonderen, auch von Kritikern k\u00f6nnen wir h\u00f6ren: Die Finanzkrise ab 2008 habe sich insofern in Grenzen gehalten, als die \u00f6konomische Kernschmelze wie 1929 \/ 30 durch rechtzeitiges Eingreifen der Zentralbanken und der nationalen Regierungen verhindert worden sei. Es muss in aller Klarheit gesagt werden: Dies gilt nur f\u00fcr das Zentrum. Dessen Banken wurden &#8222;gerettet&#8220;. In der EU geschah dies auf Kosten des Oliveng\u00fcrtels und Osteuropas. Man  \u201el\u00f6ste\u201c das Problem, indem man den S\u00fcden zerst\u00f6rte. Sehen wir doch hin! Die R\u00fcckg\u00e4nge im Sozialprodukt, die soziale Katastrophe in Griechenland und anderswo hat durchaus die Gr\u00f6\u00dfenordnung der seinerzeiti\u00adgen Weltwirtschaftskrise erreicht bzw. \u00fcbertroffen: Laut Rechnungen von <em>Maddison<\/em> ging das BIP \u00d6sterreichs vom Jahr 1929 auf 1933 um -22,5 % zur\u00fcck, jenes des Deutschen Reichs bis 1932 um -16 %. Dann begann dort wie \u00fcbrigens in den meisten anderen Volkswirtschaften und Staaten, bereits wieder ein Wachstum, . (vgl. auch <em>M\u00e4rz<\/em> 1990).<\/p>\n<p>Wirklich schlimm betroffen, noch \u00e4rger als \u00d6sterreich, waren die USA. Sie zahlten nun die Zeche daf\u00fcr, dass sie keinen institutionalen Apparat aufgebaut hatten, der ihnen eine ziel\u00adf\u00fchrende Wirtschaftspolitik \u00fcberhaupt erlaubte. Ihr BIP sank, im Vergleich zu 1929, auf 71,5. Dagegen sind die Werte von Gro\u00dfbritannien (1932: 94,9) und Frankreich (85,3) schon fast harmlos. In Gro0\u00dfbritannien war \u00fcbrigens Churchill einer der Verantwortlichen f\u00fcr den Wahnsinn, nicht nur den Goldstandard nach dem Weltkrieg wieder aufzunehmen, sondern auch noch das Pfund mit einem viel zu hohen Kurs an das Gold zu binden.<\/p>\n<p>Vergleichen wir dies mit dem Verlauf von seit 2007 in der EU-Peripherie. Das letzten Jahr vor der Finanz- und Euro-Krise soll uns Ausgangsbasis bis zur Gegenwart sein. Die Zahlen stammen von EUROSTAT (Verkn\u00fcpfte Volumens-Indizes). Griechenland st\u00fcrzte von 100 (2007) auf 74 (letzte verf\u00fcgbare Daten f\u00fcr 2014), Italien auf 91, Spanien und Portugal auf 93,8 bzw. 93,2. Dagegen tauchte die BR Deutschland zwar im Jahr auf 95,4 ab, steht aber 2014 wieder auf 105,4. Bei \u00d6sterreich lauten die Zahlen 97,7 und 103,9.<\/p>\n<p>Der Euro als <em>Automatisierung f\u00fcr die weitere und versch\u00e4rfte Peripherisierung<\/em> der bisherigen Peripherie durch die W\u00e4hrungsunion funktioniert. Der Euro ist ein Erfolg f\u00fcr die Kernl\u00e4nder. Sie k\u00e4mpfen nicht ausschlie\u00dflich aus politischen Gr\u00fcnden f\u00fcr seinen Weiterbestand. Die sind \u00fcberragend wichtig. Aber Deutschland, \u00d6sterreich, im unauff\u00e4lligen Schlepptau das Nicht-\u20ac-Land Schweden, weniger gut die Niederlande, gewinnen offenbar auch \u00f6konomisch. Aller\u00addings ist dies schon wieder so ein schlampiger Ausdruck. Es gewinnen nicht Deutschland und \u00d6sterreich: Es gewinnen jene wichtigen Kapitalfraktionen, die im Export t\u00e4tig sind.<\/p>\n<p>Die anderen Kapitalfraktionen gehen allerdings auch nicht leer aus. Denn der Euro ist nicht nur ein Automatismus der Peripherisierung. Er ist auch ein <em>Automatismus des Sozialabbaus<\/em>. L\u00e4sst sich das im Euro-Regime verhindern? Die naiven Sp\u00e4tkeynesianer wollen ja bekanntlich mit einer Ausweitung der Verschuldung und einer Aufweichung der entsprechenden Maastricht-Kriterien einen Neustart.<\/p>\n<p>Die politische Auseinandersetzung ab den 1980er Jahren, die neoliberale Wende im Westen, lief ideologisch nicht zuletzt als ein Kampf zwischen Keynesianismus und Monetarismus ab, oder wie sich Michael <em>Mann<\/em> (2001) ausdr\u00fcckte: \u201eKeynes pretends to rule within the nation-state, Adam Smith still rules without.\u201c Mit dieser passenden Wendung stellt sich die Frage: Kann es einen transnationalen oder supranationalen Keynesianismus \u00fcberhaupt geben? Welche strategische Bedeutung diese Frage hat, ergibt sich schon aus einer spezifischen heutigen Situation: Die Oppositionellen des Systemimmanenten ziehen mit Keynesianismus als Alternative durch die Lande, ob im deutschsprachigen Raum oder auch in S\u00fcdeuropa.<\/p>\n<p><strong>Eine keynesianische Wirtschaftspolitik ist in einem supranationalen Staat und auch in \u00fcbergro\u00dfen Nationalstaaten jedenfalls auf Marktbasis unm\u00f6glich<\/strong>. Jede Investition w\u00fcrde es dorthin ziehen, wo ohnehin die Gewinne bl\u00fchen. Der Keynesianismus ist vielleicht noch eine sozialpolitische Beruhigungs-Pille und ein Propaganda-Floskel. Er hat als politisches Programm einer systemimmanenten Wirtschaftspolitik in einer globalen Welt ausgedient.<\/p>\n<p>Dazu kommt noch als mindestens ebenso wichtiger Punkt: Keynesianismus i. S. dessen, was (angeblich) \u201elinke\u201c Sozialdemokraten und Gr\u00fcne m\u00f6chten, die Aufbl\u00e4hung der Staatsschuld, hei\u00dft den Teufel mit Belzebub austreiben. <em>Denn er bef\u00f6rdert durch die massive Vergr\u00f6\u00dferung der Kreditwirtschaft die Finanzialisierung<\/em>. Auch die hat mehrere Ebenen. Die auf dem ersten Blick eher harmlos erscheinende Ebene der Inhaber von Staatsschuldscheinen ist mittel- und langfristig einer der Wege in die Katastrophe.<\/p>\n<p>Den wichtigsten Punkt k\u00f6nnen woir hier aber nur k\u00fcrzest andeuten. Wir werden ihn ein anderes Mal ausf\u00fchren. Hier stehen sich zwei Prinzipien der Politik gegen\u00fcber. Nationale Politik bedeutete den umfassenden Vorsorgestaat. Mit ihm wollte man die Unter- und Mittelschichten integrieren, und das ist auch gelungen.<\/p>\n<p>Dem steht die globale Politik des Kapitals als eigenst\u00e4ndig Handelnden gegen\u00fcber. Aber das w\u00e4re ein Widerspruch in sich. Das Kapital kann nicht sein eigener handlungsf\u00e4higer Gesamt\u00adkapitalist sein. Dazu sind die inneren Widerspr\u00fcche zwischen den \u201efeindlichen Br\u00fcdern\u201c zu gro\u00df. Es muss sich also seinen eigenen rudiment\u00e4ren Staat aufbauen. Das ist der Supra-nationale Staat, das regionale Imperium EU.<\/p>\n<p style=\"text-align: right;\">Albert F. Reiterer, 6. April 2016<\/p>\n<p><em> <\/em><\/p>\n<p><em>Mann, Michael<\/em> (2001), Globalizatio Is (Among Other Things) Transnational, International and American. In: Science and Society 65, 464 \u2013 469.<\/p>\n<p><em>M\u00e4rz, Eduard<\/em> (1990), , Die gro\u00dfe Depression in \u00d6sterreich, 1930 \u2013 1933. In: Wirtschaft und Gesellschaft 16, 409 \u2013 438-<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nicht nur von Verteidigern dieses Systems und der EU im Besonderen, auch von Kritikern k\u00f6nnen wir h\u00f6ren: Die Finanzkrise ab &hellip; <a href=\"https:\/\/www.euroexit.org\/index.php\/2016\/04\/06\/wahrungsunion-und-die-verelendung-der-europaischen-peripherie\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eW\u00c4HRUNGSUNION UND DIE VERELENDUNG DER EUROP\u00c4ISCHEN PERIPHERIE\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-742","post","type-post","status-publish","format-standard","hentry","category-home"],"author_meta":{"display_name":"Albert Reiterer","author_link":"https:\/\/www.euroexit.org\/index.php\/author\/albert\/"},"featured_img":null,"coauthors":[],"tax_additional":{"categories":{"linked":["<a href=\"https:\/\/www.euroexit.org\/index.php\/category\/home\/\" class=\"advgb-post-tax-term\">Home<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Home<\/span>"]}},"comment_count":"0","relative_dates":{"created":"Ver\u00f6ffentlicht 10\u00a0Jahren vor","modified":"Aktualisiert 9\u00a0Jahren vor"},"absolute_dates":{"created":"Ver\u00f6ffentlicht am 6. April 2016","modified":"Aktualisiert am 20. Februar 2017"},"absolute_dates_time":{"created":"Ver\u00f6ffentlicht am 6. April 2016 14:58","modified":"Aktualisiert am 20. Februar 2017 1:10"},"featured_img_caption":"","series_order":"","_links":{"self":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/742"}],"collection":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/comments?post=742"}],"version-history":[{"count":0,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/posts\/742\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/media?parent=742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/categories?post=742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.euroexit.org\/index.php\/wp-json\/wp\/v2\/tags?post=742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}